{"id":3,"date":"2024-05-23T10:32:19","date_gmt":"2024-05-23T08:32:19","guid":{"rendered":"https:\/\/businessenglishavenue.com\/?page_id=3"},"modified":"2025-03-13T17:31:37","modified_gmt":"2025-03-13T16:31:37","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/businessenglishavenue.com\/es\/privacy-policy\/","title":{"rendered":"Pol\u00edtica de privacidad"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"3\" class=\"elementor elementor-3\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b434c22 e-flex e-con-boxed e-con e-parent\" data-id=\"b434c22\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e47fce3 e-con-full e-flex e-con e-child\" data-id=\"e47fce3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5aaf4a1 elementor-widget elementor-widget-heading\" data-id=\"5aaf4a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Pol\u00edtica de privacidad<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-635933f e-flex e-con-boxed e-con e-parent\" data-id=\"635933f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e522268 elementor-widget elementor-widget-text-editor\" data-id=\"e522268\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>I. POL\u00cdTICA DE PRIVACIDAD Y PROTECCI\u00d3N DE DATOS<br \/>En cumplimiento de lo dispuesto en la normativa vigente, English Avenue (en adelante tambi\u00e9n el Sitio Web) se compromete a adoptar las medidas t\u00e9cnicas y organizativas necesarias, seg\u00fan el nivel de seguridad adecuado al riesgo de los datos recogidos.<\/p><p>Leyes que incorpora esta pol\u00edtica de privacidad<br \/>Esta pol\u00edtica de privacidad est\u00e1 adaptada a la normativa vigente espa\u00f1ola y europea sobre protecci\u00f3n de datos de car\u00e1cter personal en Internet. En concreto, cumple con la siguiente normativa:<\/p><p>Reglamento (UE) 2016\/679 del Parlamento Europeo y del Consejo, de 27 de abril de 2016, relativo a la protecci\u00f3n de las personas f\u00edsicas en lo que respecta al tratamiento de datos personales y a la libre circulaci\u00f3n de estos datos (RGPD).<br \/>Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de Datos Personales y Garant\u00eda de los Derechos Digitales (LOPD-GDD).<br \/>Real Decreto 1720\/2007, de 21 de diciembre, por el que se aprueba el Reglamento de desarrollo de la Ley Org\u00e1nica 15\/1999, de 13 de diciembre, de Protecci\u00f3n de Datos de Car\u00e1cter Personal (RDLOPD).<br \/>Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y Comercio Electr\u00f3nico (LSSI-CE).<br \/>Identidad del responsable del tratamiento de datos personales<br \/>El responsable del tratamiento de los datos personales recogidos en English Avenue es: Joshua John Weatherburn, con NIF: Y7937054 (en adelante, Responsable del Tratamiento). Sus datos de contacto son los siguientes:<\/p><p>Direcci\u00f3n: C\/ Pasi\u00f3n, 2 bajo.<\/p><p>Tel\u00e9fono de contacto: 611697741<\/p><p>Correo electr\u00f3nico de contacto: englishavenuevalladolid@gmail.com<\/p><p>Registro de datos personales<br \/>En cumplimiento de lo establecido en el GDPR y en la LOPD-GDD, le informamos que los datos personales recabados por English Avenue, a trav\u00e9s de los formularios sitos en sus p\u00e1ginas, ser\u00e1n incorporados y tratados en nuestro fichero con la finalidad de poder facilitar, agilizar y cumplir los compromisos establecidos entre English Avenue y el Usuario o el mantenimiento de la relaci\u00f3n que se establezca en los formularios que el Usuario rellene, o para atender una solicitud o consulta del Usuario. Asimismo, de conformidad con lo dispuesto en el GDPR y en la LOPD-GDD, salvo que resulte de aplicaci\u00f3n la excepci\u00f3n prevista en el art\u00edculo 30.5 del GDPR, se mantiene un registro de actividades de tratamiento en el que se especifican, en funci\u00f3n de sus finalidades, las actividades de tratamiento llevadas a cabo y las dem\u00e1s circunstancias establecidas en el GDPR.<\/p><p>Principios aplicables al tratamiento de datos personales<br \/>El tratamiento de los datos personales del Usuario estar\u00e1 sujeto a los siguientes principios recogidos en el art\u00edculo 5 del GDPR y en el art\u00edculo 4 y siguientes de la Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de Datos Personales y garant\u00eda de los derechos digitales:<\/p><p>Principio de licitud, lealtad y transparencia: se requerir\u00e1 en todo momento el consentimiento del Usuario previa informaci\u00f3n completamente transparente de las finalidades para las que se recaban los datos personales.<br \/>Principio de limitaci\u00f3n de la finalidad: los datos personales se recoger\u00e1n con fines espec\u00edficos, expl\u00edcitos y leg\u00edtimos.<br \/>Principio de minimizaci\u00f3n de datos: los datos personales recogidos ser\u00e1n \u00fanicamente los estrictamente necesarios en relaci\u00f3n con los fines para los que son tratados.<br \/>Principio de exactitud: los datos personales deben ser exactos y estar siempre actualizados.<br \/>Principio de limitaci\u00f3n del plazo de conservaci\u00f3n: los datos personales s\u00f3lo se conservar\u00e1n de forma que permitan la identificaci\u00f3n del Usuario durante el tiempo necesario para los fines de su tratamiento.<br \/>Principio de integridad y confidencialidad: los datos personales se tratar\u00e1n de forma que se garantice su seguridad y confidencialidad.<br \/>Principio de responsabilidad proactiva: el Responsable del Tratamiento ser\u00e1 responsable de garantizar el cumplimiento de los principios anteriores.<br \/>Categor\u00edas de datos personales<br \/>Las categor\u00edas de datos tratadas por English Avenue son \u00fanicamente datos identificativos. En ning\u00fan caso se tratan categor\u00edas especiales de datos personales en el sentido del art\u00edculo 9 del RGPD.<\/p><p>Base jur\u00eddica para el tratamiento de datos personales<br \/>La base legal para el tratamiento de los datos personales es el consentimiento. English Avenue se compromete a obtener el consentimiento expreso y verificable del Usuario para el tratamiento de sus datos personales para uno o varios fines espec\u00edficos.<\/p><p>El Usuario tendr\u00e1 derecho a retirar su consentimiento en cualquier momento. Ser\u00e1 tan f\u00e1cil retirar el consentimiento como darlo. Por regla general, la retirada del consentimiento no afectar\u00e1 al uso del Sitio Web.<\/p><p>En las ocasiones en que el Usuario deba o pueda facilitar sus datos a trav\u00e9s de formularios para realizar consultas, solicitar informaci\u00f3n o por motivos relacionados con el contenido del Sitio Web, se le informar\u00e1 si la cumplimentaci\u00f3n de alguno de ellos es obligatoria por resultar imprescindible para el correcto desarrollo de la operaci\u00f3n realizada.<\/p><p>Fines del tratamiento de datos personales<br \/>Los datos personales son recabados y gestionados por English Avenue con la finalidad de poder facilitar, agilizar y cumplir los compromisos establecidos entre el Sitio Web y el Usuario o el mantenimiento de la relaci\u00f3n que se establezca en los formularios que este \u00faltimo rellene o para atender una solicitud o consulta.<\/p><p>Asimismo, los datos podr\u00e1n ser utilizados con finalidades comerciales de personalizaci\u00f3n, explotaci\u00f3n y estad\u00edsticas, y actividades propias del objeto social de English Avenue, as\u00ed como para la extracci\u00f3n, almacenamiento de datos y estudios de marketing para adecuar los Contenidos ofrecidos al Usuario, as\u00ed como para mejorar la calidad, funcionamiento y navegaci\u00f3n por el Sitio Web.<\/p><p>En el momento en que se obtengan los datos personales, se informar\u00e1 al Usuario sobre la finalidad o finalidades espec\u00edficas para las que se tratar\u00e1n los datos personales; es decir, el uso o usos que se dar\u00e1n a la informaci\u00f3n recabada.<\/p><p>Periodos de conservaci\u00f3n de datos personales<br \/>Los datos de car\u00e1cter personal s\u00f3lo se conservar\u00e1n durante el tiempo m\u00ednimo necesario para los fines de su tratamiento y, en todo caso, s\u00f3lo durante el plazo siguiente: 12, o hasta que el Usuario solicite su supresi\u00f3n.<\/p><p>En el momento de la obtenci\u00f3n de los datos personales, se informar\u00e1 al Usuario del plazo de conservaci\u00f3n de los mismos o, cuando ello no sea posible, de los criterios seguidos para determinar dicho plazo.<\/p><p>Destinatarios de los datos personales<br \/>Los datos personales del Usuario se compartir\u00e1n con los siguientes destinatarios o categor\u00edas de destinatarios:<\/p><p>En el caso de que el Responsable del Tratamiento pretenda transferir datos personales a un tercer pa\u00eds u organizaci\u00f3n internacional, en el momento de la obtenci\u00f3n de los datos personales se informar\u00e1 al Usuario sobre el tercer pa\u00eds u organizaci\u00f3n internacional al que se pretende transferir los datos, as\u00ed como de la existencia o no de una decisi\u00f3n de adecuaci\u00f3n por parte de la Comisi\u00f3n.<\/p><p>Datos personales de menores<br \/>En cumplimiento de lo dispuesto en los art\u00edculos 8 del GDPR y 7 de la Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de Datos Personales y Garant\u00eda de los Derechos Digitales, \u00fanicamente los mayores de 14 a\u00f1os podr\u00e1n prestar su consentimiento para el tratamiento l\u00edcito de sus datos personales por parte de English Avenue. Si la persona es menor de 14 a\u00f1os, se requerir\u00e1 el consentimiento de los padres o tutores para el tratamiento, y \u00e9ste s\u00f3lo se considerar\u00e1 l\u00edcito en la medida en que lo hayan autorizado.<\/p><p>Confidencialidad y seguridad de los datos personales<br \/>English Avenue se compromete a adoptar las medidas t\u00e9cnicas y organizativas necesarias, seg\u00fan el nivel de seguridad adecuado al riesgo de los datos recogidos, para garantizar la seguridad de los datos de car\u00e1cter personal y evitar la destrucci\u00f3n, p\u00e9rdida o alteraci\u00f3n accidental o il\u00edcita de datos personales transmitidos, conservados o tratados de otra forma, o la comunicaci\u00f3n o acceso no autorizados a dichos datos.<\/p><p>El Sitio Web dispone de un certificado SSL (Secure Socket Layer), que garantiza que los datos personales se transmiten de forma segura y confidencial, ya que la transmisi\u00f3n de datos entre el servidor y el Usuario, y en retroalimentaci\u00f3n, est\u00e1 totalmente encriptada.<\/p><p>No obstante, dado que English Avenue no puede garantizar la inexpugnabilidad de la red Internet ni la ausencia total de hackers u otros que accedan de modo fraudulento a los datos personales, el Responsable del Tratamiento se compromete a comunicar al Usuario sin dilaci\u00f3n indebida cuando ocurra una violaci\u00f3n de la seguridad de los datos personales que sea probable que entra\u00f1e un alto riesgo para los derechos y libertades de las personas f\u00edsicas. De conformidad con el art\u00edculo 4 del RGPD, se entiende por violaci\u00f3n de la seguridad de los datos personales cualquier violaci\u00f3n de la seguridad que provoque la destrucci\u00f3n, accidental o il\u00edcita, la p\u00e9rdida o alteraci\u00f3n de datos personales transmitidos, conservados o tratados de otra forma, o la comunicaci\u00f3n o acceso no autorizados a dichos datos.<\/p><p>Los datos personales ser\u00e1n tratados de forma confidencial por el Responsable del Tratamiento, quien se compromete a informar y garantizar mediante una obligaci\u00f3n legal o contractual que dicha confidencialidad es respetada por sus empleados, asociados y cualquier persona a la que haga accesible la informaci\u00f3n.<\/p><p>Derechos derivados del tratamiento de datos personales<br \/>El Usuario tiene sobre English Avenue y podr\u00e1, por tanto, ejercitar frente al Responsable del Tratamiento los siguientes derechos reconocidos en el GDPR y en la Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de Datos Personales y garant\u00eda de los derechos digitales:<\/p><p>Derecho de acceso: Es el derecho del Usuario a obtener confirmaci\u00f3n sobre si English Avenue est\u00e1 tratando o no sus datos personales y, en tal caso, obtener informaci\u00f3n sobre sus datos concretos de car\u00e1cter personal y del tratamiento que English Avenue haya realizado o realice, as\u00ed como, entre otra, de la informaci\u00f3n disponible sobre el origen de dichos datos y los destinatarios de las comunicaciones realizadas o previstas de los mismos.<br \/>Derecho de rectificaci\u00f3n: Es el derecho del Usuario a que sus datos personales sean modificados si se comprueba que son inexactos o, teniendo en cuenta los fines del tratamiento, incompletos.<br \/>Derecho de supresi\u00f3n (\"derecho al olvido\"): Es el derecho del Usuario, siempre que la legislaci\u00f3n vigente no establezca lo contrario, a obtener la supresi\u00f3n de sus datos personales cuando ya no sean necesarios para los fines para los que fueron recogidos o tratados; el Usuario haya retirado su consentimiento al tratamiento y no exista otro fundamento jur\u00eddico para ello; el Usuario se oponga al tratamiento y no exista otro motivo leg\u00edtimo para continuar con \u00e9l; los datos personales hayan sido tratados de forma il\u00edcita; los datos personales deban suprimirse en cumplimiento de una obligaci\u00f3n legal; o los datos personales se hayan obtenido como resultado de una oferta directa de servicios de la sociedad de la informaci\u00f3n a un menor de 14 a\u00f1os. Adem\u00e1s de suprimir los datos, el responsable del tratamiento, teniendo en cuenta la tecnolog\u00eda disponible y el coste de su aplicaci\u00f3n, deber\u00e1 adoptar medidas razonables para informar a los responsables que est\u00e9n tratando los datos personales de la solicitud del interesado de suprimir cualquier v\u00ednculo con dichos datos personales.<br \/>Derecho a la limitaci\u00f3n del tratamiento: Es el derecho del Usuario a limitar el tratamiento de sus datos personales. El Usuario tiene derecho a obtener la limitaci\u00f3n del tratamiento cuando impugne la exactitud de sus datos personales; el tratamiento sea il\u00edcito; el Responsable del Tratamiento ya no necesite los datos personales, pero el Usuario los necesite para presentar reclamaciones; y cuando el Usuario se haya opuesto al tratamiento.<br \/>Derecho a la portabilidad de los datos: En caso de que el tratamiento se realice por medios automatizados, el Usuario tendr\u00e1 derecho a recibir del Responsable del Tratamiento sus datos personales en un formato estructurado, de uso com\u00fan y lectura mec\u00e1nica, y a transmitirlos a otro responsable del tratamiento. Siempre que sea t\u00e9cnicamente posible, el responsable del tratamiento transmitir\u00e1 directamente los datos a ese otro responsable.<br \/>Derecho de oposici\u00f3n: Es el derecho del Usuario a que no se lleve a cabo el tratamiento de sus datos de car\u00e1cter personal o se cese el tratamiento de los mismos por parte de English Avenue.<br \/>Derecho a no ser objeto de una decisi\u00f3n basada \u00fanicamente en un tratamiento automatizado, incluida la elaboraci\u00f3n de perfiles: Es el derecho del Usuario a no ser objeto de una decisi\u00f3n individualizada basada \u00fanicamente en el tratamiento automatizado de sus datos personales, incluida la elaboraci\u00f3n de perfiles, salvo que la legislaci\u00f3n vigente disponga otra cosa.<br \/>As\u00ed, el Usuario podr\u00e1 ejercitar sus derechos mediante comunicaci\u00f3n escrita dirigida al Responsable del Tratamiento con la referencia \"RGPD-\", especificando:<\/p><p>Nombre, apellidos del Usuario y copia del DNI. En los casos en que se admita la representaci\u00f3n, tambi\u00e9n ser\u00e1 necesaria la identificaci\u00f3n por el mismo medio de la persona que represente al Usuario, as\u00ed como el documento acreditativo de la representaci\u00f3n. La fotocopia del DNI podr\u00e1 ser sustituida por cualquier otro medio v\u00e1lido en derecho que acredite la identidad.<br \/>Solicitud con los motivos concretos de la solicitud o informaci\u00f3n a la que se pretende acceder.<br \/>Direcci\u00f3n a efectos de notificaci\u00f3n.<br \/>Fecha y firma del solicitante.<br \/>Cualquier documento que acredite la solicitud realizada.<br \/>Esta solicitud y cualquier otro documento adjunto pueden enviarse a la siguiente direcci\u00f3n y\/o correo electr\u00f3nico:<\/p><p>Direcci\u00f3n postal: C\/ Pasi\u00f3n, 2 bajo.<\/p><p>Correo electr\u00f3nico: englishavenuevalladolid@gmail.com<\/p><p>Enlaces a sitios web de terceros<br \/>El Sitio Web puede incluir hiperv\u00ednculos o enlaces que permiten el acceso a p\u00e1ginas web de terceros distintos de English Avenue, y que por tanto no son operados por English Avenue. Los titulares de estas p\u00e1ginas web tendr\u00e1n sus propias pol\u00edticas de protecci\u00f3n de datos, siendo ellos mismos responsables, en cada caso, de sus propios ficheros y de sus propias pr\u00e1cticas de privacidad.<\/p><p>Reclamaciones a la autoridad de control<br \/>Si el Usuario considera que existe un problema o infracci\u00f3n de la normativa vigente en la forma en que se est\u00e1n tratando sus datos personales, tendr\u00e1 derecho a la tutela judicial efectiva y a presentar una reclamaci\u00f3n ante una autoridad de control, en particular, en el Estado en el que tenga su residencia habitual, lugar de trabajo o lugar de la presunta infracci\u00f3n. En el caso de Espa\u00f1a, la autoridad de control es la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos (https:\/\/www.aepd.es\/).<\/p><p>II. ACEPTACI\u00d3N Y MODIFICACIONES DE LA PRESENTE POL\u00cdTICA DE PRIVACIDAD<br \/>El Usuario deber\u00e1 haber le\u00eddo y estar conforme con las condiciones sobre protecci\u00f3n de datos de car\u00e1cter personal contenidas en la presente Pol\u00edtica de Privacidad, as\u00ed como aceptar el tratamiento de sus datos personales para que el Responsable del Tratamiento pueda proceder al mismo en la forma, durante los plazos y para las finalidades indicadas. El uso del Sitio Web implicar\u00e1 la aceptaci\u00f3n de la Pol\u00edtica de Privacidad del Sitio Web.<\/p><p>English Avenue se reserva el derecho a modificar su Pol\u00edtica de Privacidad, de acuerdo a su propio criterio, o motivado por un cambio legislativo, jurisprudencial o doctrinal de la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos. Los cambios o actualizaciones de esta Pol\u00edtica de Privacidad no ser\u00e1n notificados expresamente al Usuario. Se recomienda al Usuario que consulte peri\u00f3dicamente esta p\u00e1gina para conocer los \u00faltimos cambios o actualizaciones.<\/p><p>Esta Pol\u00edtica de Privacidad ha sido actualizada para cumplir con el Reglamento (UE) 2016\/679 del Parlamento Europeo y del Consejo, de 27 de abril de 2016, relativo a la protecci\u00f3n de las personas f\u00edsicas en lo que respecta al tratamiento de datos personales y a la libre circulaci\u00f3n de estos datos (GDPR) y la Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de Datos Personales y Garant\u00eda de los Derechos Digitales.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Privacy Policy I. PRIVACY AND DATA PROTECTION POLICYIn compliance with the provisions of current legislation, English Avenue (hereinafter also the Website) undertakes to adopt the necessary technical and organisational measures, according to the level of security appropriate to the risk of the data collected. Laws that this privacy policy incorporatesThis privacy policy is adapted to [&hellip;]<\/p>","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Privacy Policy - English Avenue<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacy Policy - English Avenue\" \/>\n<meta property=\"og:description\" content=\"Privacy Policy I. PRIVACY AND DATA PROTECTION POLICYIn compliance with the provisions of current legislation, English Avenue (hereinafter also the Website) undertakes to adopt the necessary technical and organisational measures, according to the level of security appropriate to the risk of the data collected. Laws that this privacy policy incorporatesThis privacy policy is adapted to [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/businessenglishavenue.com\/es\/privacy-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"English Avenue\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-13T16:31:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/businessenglishavenue.com\\\/privacy-policy\\\/\",\"url\":\"https:\\\/\\\/businessenglishavenue.com\\\/privacy-policy\\\/\",\"name\":\"Privacy Policy - English Avenue\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/businessenglishavenue.com\\\/#website\"},\"datePublished\":\"2024-05-23T08:32:19+00:00\",\"dateModified\":\"2025-03-13T16:31:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/businessenglishavenue.com\\\/privacy-policy\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/businessenglishavenue.com\\\/privacy-policy\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/businessenglishavenue.com\\\/privacy-policy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/businessenglishavenue.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy Policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/businessenglishavenue.com\\\/#website\",\"url\":\"https:\\\/\\\/businessenglishavenue.com\\\/\",\"name\":\"English Avenue\",\"description\":\"Online Meditation Courses Website\",\"publisher\":{\"@id\":\"https:\\\/\\\/businessenglishavenue.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/businessenglishavenue.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/businessenglishavenue.com\\\/#organization\",\"name\":\"English Avenue\",\"url\":\"https:\\\/\\\/businessenglishavenue.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/businessenglishavenue.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/businessenglishavenue.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/busniess-english-avenue.png\",\"contentUrl\":\"https:\\\/\\\/businessenglishavenue.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/busniess-english-avenue.png\",\"width\":601,\"height\":556,\"caption\":\"English Avenue\"},\"image\":{\"@id\":\"https:\\\/\\\/businessenglishavenue.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Privacy Policy - English Avenue","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Privacy Policy - English Avenue","og_description":"Privacy Policy I. PRIVACY AND DATA PROTECTION POLICYIn compliance with the provisions of current legislation, English Avenue (hereinafter also the Website) undertakes to adopt the necessary technical and organisational measures, according to the level of security appropriate to the risk of the data collected. Laws that this privacy policy incorporatesThis privacy policy is adapted to [&hellip;]","og_url":"https:\/\/businessenglishavenue.com\/es\/privacy-policy\/","og_site_name":"English Avenue","article_modified_time":"2025-03-13T16:31:37+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/businessenglishavenue.com\/privacy-policy\/","url":"https:\/\/businessenglishavenue.com\/privacy-policy\/","name":"Privacy Policy - English Avenue","isPartOf":{"@id":"https:\/\/businessenglishavenue.com\/#website"},"datePublished":"2024-05-23T08:32:19+00:00","dateModified":"2025-03-13T16:31:37+00:00","breadcrumb":{"@id":"https:\/\/businessenglishavenue.com\/privacy-policy\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/businessenglishavenue.com\/privacy-policy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/businessenglishavenue.com\/privacy-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/businessenglishavenue.com\/"},{"@type":"ListItem","position":2,"name":"Privacy Policy"}]},{"@type":"WebSite","@id":"https:\/\/businessenglishavenue.com\/#website","url":"https:\/\/businessenglishavenue.com\/","name":"Avenida de Inglaterra","description":"P\u00e1gina web de cursos de meditaci\u00f3n en l\u00ednea","publisher":{"@id":"https:\/\/businessenglishavenue.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/businessenglishavenue.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/businessenglishavenue.com\/#organization","name":"Avenida de Inglaterra","url":"https:\/\/businessenglishavenue.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/businessenglishavenue.com\/#\/schema\/logo\/image\/","url":"https:\/\/businessenglishavenue.com\/wp-content\/uploads\/2024\/09\/busniess-english-avenue.png","contentUrl":"https:\/\/businessenglishavenue.com\/wp-content\/uploads\/2024\/09\/busniess-english-avenue.png","width":601,"height":556,"caption":"English Avenue"},"image":{"@id":"https:\/\/businessenglishavenue.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/businessenglishavenue.com\/es\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/businessenglishavenue.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/businessenglishavenue.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/businessenglishavenue.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/businessenglishavenue.com\/es\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":23,"href":"https:\/\/businessenglishavenue.com\/es\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":2433,"href":"https:\/\/businessenglishavenue.com\/es\/wp-json\/wp\/v2\/pages\/3\/revisions\/2433"}],"wp:attachment":[{"href":"https:\/\/businessenglishavenue.com\/es\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}